{"id":464,"date":"2015-02-07T07:41:54","date_gmt":"2015-02-07T07:41:54","guid":{"rendered":"http:\/\/wp.nootheme.com\/jobelementor\/?page_id=464"},"modified":"2015-02-11T08:11:35","modified_gmt":"2015-02-11T08:11:35","slug":"member","status":"publish","type":"page","link":"https:\/\/wp.nootheme.com\/jobelementor\/member\/","title":{"rendered":"Member"},"content":{"rendered":"\t\t\t\t<div class=\"account-form show-login-form-links\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"account-log-form\">\n\t\t\t\t\t\t\t\t\n<form method=\"POST\" style=\"max-width: 600px; margin: auto\" class=\"noo-ajax-login-form form-horizontal\" action=\"https:\/\/wp.nootheme.com\/jobelementor\/member\/?action=login&redirect_to=https%3A%2F%2Fwp.nootheme.com%2Fjobelementor%2Fwp-json%2Fwp%2Fv2%2Fpages%2F464%3Flogged_in%3D1\">\n\t<div style=\"display: none\">\n\t\t<input type=\"hidden\" name=\"action\" value=\"noo_ajax_login\">\n\t\t<input type=\"hidden\" class=\"security\" name=\"security\" value=\"7f527ebde3\" \/>\n\t<\/div>\n\t<div class=\"form-group text-center noo-ajax-result\" style=\"display: none\"><\/div>\n\t    <div class=\"noo-login-demo\" style=\"text-align: center\">\n        <a style=\"padding: 10px 20px;\" class=\"btn btn-primary\"\n           href=\"https:\/\/wp.nootheme.com\/jobelementor?action=login_demo&#038;login_role=candidate\">Candidate Login<\/a>\n        <a style=\"padding: 10px 20px;\" class=\"btn btn-primary\"\n           href=\"https:\/\/wp.nootheme.com\/jobelementor?action=login_demo&#038;login_role=employer\">Employer Login<\/a>\n    <\/div>\n    \t\t\t<div class=\"form-group row login-socical login-socical-new\">\n\t\t\t    <div class=\"col-sm-12 col-xs-12\">\n\t\t\t    \t\t\t\t    \t\n\t\t\t    \t\t<div class=\"button_socical fb\">\n\t\t\t    \t\t\t<i data-id=\"6a047500e9fe5\" id=\"6a047500e9fe5\" class=\"fab fa-facebook-f\"><\/i>\n\t\t\t\t    \t\t<em data-id=\"6a047500e9fe5\" class=\"fa-facebook\">Login with Facebook<\/em>\n\t\t\t    \t\t<\/div>\n\n\t\t\t    \t\t\t\t    \t\t\t\t    \t\t<div class=\"button_socical gg\" id=\"google_login_6a047500e9fe9\">\n\t\t\t    \t\t\t<!-- <img src=\"https:\/\/wp.nootheme.com\/jobmonster\/wp-content\/themes\/noo-jobmonster\/assets\/images\/btn_google_signin.png\" data-id=\"6a047500e9fe6\" id=\"i_6a047500e9fe6\" \/> -->\n                            <i data-id=\"6a047500e9fe6\" id=\"i_6a047500e9fe6\" class=\"fab fa-google\"><\/i>\n                            <em data-id=\"6a047500e9fe6\" id=\"6a047500e9fe6\" class=\"fa-google\">Login with Google<\/em>\n\t\t\t    \t\t<\/div>\n\t\t\t    \t\t\t\t    \t                        \n                        <div class=\"button_socical linkedin\">\n                            <a class=\"link login\" href=\"https:\/\/www.linkedin.com\/uas\/oauth2\/authorization?client_id=81uu0ss2lr6wnr&redirect_uri=https%3A%2F%2Fwp.nootheme.com%2Fjobelementor%2F&response_type=code&scope=r_liteprofile+r_emailaddress&state=SduqchYyPdD1\">\n                                <i data-id=\"6a047500e9fe7\" id=\"6a047500e9fe7\" class=\"fab fa-linkedin-in\"><\/i>\n                                <em data-id=\"6a047500e9fe7\" class=\"fa-linkedin-in\">Login with LinkedIn<\/em>\n                            <\/a>\n                        <\/div>\n                    \t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t<div class=\"form-group row required-field\">\n\t\t<label for=\"6a047500e9edf_log\" class=\"col-sm-3 control-label\">\n\t\t\t\t\t\t\tUsername\t\t\t\t\t<\/label>\n\t\t<div class=\"col-sm-9\">\n\t\t\t<input type=\"text\" class=\"log form-control\" id=\"6a047500e9edf_log\" name=\"log\" required value=\"\" placeholder=\"Username\">\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-group row required-field\">\n\t\t<label for=\"6a047500e9edf_pwd\" class=\"col-sm-3 control-label\">Password<\/label>\n\t\t<div class=\"col-sm-9\">\n\t\t\t<input type=\"password\" id=\"6a047500e9edf_pwd\" class=\"pwd form-control\" required value=\"\" name=\"pwd\" placeholder=\"Password\">\n\t\t<\/div>\n\t<\/div>\n\n\t\n\t<div class=\"form-group row\">\n\t    <div class=\"col-sm-9 col-sm-offset-3\">\n\t    \t<div class=\"checkbox\">\n\t    \t\t<div class=\"form-control-flat\"><label class=\"checkbox\"><input type=\"checkbox\" id=\"6a047500e9edf_rememberme\" class=\"rememberme\" name=\"rememberme\"  value=\"forever\"><i><\/i> Remember Me<\/label><\/div>\n\t\t    <\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-actions form-group text-center\">\n\t \t\t \t\t<input type=\"hidden\" class=\"redirect_to\" name=\"redirect_to\" value=\"https:\/\/wp.nootheme.com\/jobelementor\/wp-json\/wp\/v2\/pages\/464?logged_in=1\" \/>\n\t \t\t \t<button type=\"submit\" class=\"btn btn-primary\">Login<\/button>\n\t \t<div class=\"login-form-links\">\n\t \t\t<span><a href=\"https:\/\/wp.nootheme.com\/jobelementor\/member\/forgot-password\/\"><i class=\"fa fa-question-circle\"><\/i> Forgot Password?<\/a><\/span>\n\t \t\t\t \t<\/div>\n\t <\/div>\n\t <\/form>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    \t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/wp.nootheme.com\/jobelementor\/wp-json\/wp\/v2\/pages\/464"}],"collection":[{"href":"https:\/\/wp.nootheme.com\/jobelementor\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wp.nootheme.com\/jobelementor\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wp.nootheme.com\/jobelementor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.nootheme.com\/jobelementor\/wp-json\/wp\/v2\/comments?post=464"}],"version-history":[{"count":0,"href":"https:\/\/wp.nootheme.com\/jobelementor\/wp-json\/wp\/v2\/pages\/464\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.nootheme.com\/jobelementor\/wp-json\/wp\/v2\/media?parent=464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}